{"id":16111,"date":"2024-09-25T23:25:36","date_gmt":"2024-09-25T23:25:36","guid":{"rendered":"https:\/\/itra.tg\/?p=16111"},"modified":"2024-09-26T18:51:50","modified_gmt":"2024-09-26T18:51:50","slug":"planification-reussie-du-centre-national-de-specialisation-cns-bioagresseurs-du-togo-2","status":"publish","type":"post","link":"https:\/\/itra.tg\/index.php\/2024\/09\/25\/planification-reussie-du-centre-national-de-specialisation-cns-bioagresseurs-du-togo-2\/","title":{"rendered":"Planification r\u00e9ussie du Centre National de Sp\u00e9cialisation (CNS) bioagresseurs du Togo"},"content":{"rendered":"\n<p>S\u2019inscrivant dans la dynamique de CNS pr\u00f4n\u00e9 par le Conseil ouest et centre africain pour la recherche et le d\u00e9veloppement agricole (CORAF), le Togo, via l\u2019Institut Togolais de Recherche Agronomique (ITRA) se positionne sur les bioagresseurs. Dans l\u2019optique de prendre en compte les priorit\u00e9s de la sous-r\u00e9gion ouest africaine concernant les probl\u00e8mes li\u00e9s ravageurs et maladies des cultures et des animaux d\u2019\u00e9levage, des experts nationaux et r\u00e9gionaux de plusieurs sp\u00e9cialit\u00e9s en lien avec ladite th\u00e9matique se sont regroup\u00e9s autour de l\u2019\u00e9quipe de l\u2019ITRA \u00e0 Lom\u00e9 du 09 au 11 ao\u00fbt 2023. Il s\u2019agit notamment des phytopathologistes, des entomologistes, des n\u00e9matologistes, des malherbologistes, des v\u00e9t\u00e9rinaires du Togo et d\u2019autres pays membres de la Communaut\u00e9 Economique des Etats de l\u2019Afrique de l\u2019Ouest (CEDEAO) et du Tchad. \u00ab Individuellement, nos centres de recherche sont oblig\u00e9s de se battre sur tous les fronts avec des ressources financi\u00e8res qui ne suivent pas souvent et aussi souvent avec un personnel limit\u00e9, \u00bb a analys\u00e9 Professeur Lamien Ni\u00e9yidouba, gestionnaire de programme au CORAF. Depuis l\u2019adoption du Programme D\u00e9taill\u00e9 du D\u00e9veloppement de l\u2019Agriculture en Afrique (PDDAA) en 2003, les Chefs d\u2019\u00c9tat se sont inscrits dans une dynamique d\u2019int\u00e9gration. Sur le plan de la recherche, il a \u00e9t\u00e9 jug\u00e9 opportun d\u2019aller vers une mutualisation des efforts de recherche. \u00ab Au lieu que chaque pays se d\u00e9ploie seul, on va s\u2019entendre pour responsabiliser un pays sur la base de ses avantages comparatifs par rapport \u00e0 une cha\u00eene de valeur et il va travailler avec l\u2019expertise de la r\u00e9gion pour g\u00e9n\u00e9rer des technologies dont les producteurs ont besoin pour transformer leur agriculture, \u00bb a pr\u00e9cis\u00e9 Professeur Lamien. Le Togo prend le train en marche Avant le Togo, le CORAF a facilit\u00e9 la mise en place des CNS ma\u00efs au Benin, c\u00e9r\u00e9ales s\u00e8ches au S\u00e9n\u00e9gal, b\u00e9tail au Niger, fruits et l\u00e9gumes au Burkina Faso, racine et tubercule au Ghana, riz au Mali, banane plantain en C\u00f4te d\u2019Ivoire, aquaculture au Nigeria, et le riz de mangrove en Sierra Leone. \u00ab L\u2019importance de ce CNS dans la r\u00e9solution d\u2019un nombre consid\u00e9rable de probl\u00e8mes agricoles rencontr\u00e9s dans tous les pays d\u00e9note avec certitude la n\u00e9cessit\u00e9 d\u2019effectuer une planification \u00e0 l\u2019\u00e9chelle r\u00e9gionale de ses activit\u00e9s et projets de recherche, \u00bb a soulign\u00e9 Dr LOMBO Yao, directeur g\u00e9n\u00e9ral de l\u2019ITRA \u00e0 l\u2019ouverture des travaux. Pour favoriser une mont\u00e9e en puissance de son CNS bioagresseurs, le Togo va devoir capitaliser sur les exp\u00e9riences de ses pr\u00e9d\u00e9cesseurs. \u00c0 l\u2019issue des trois jours de travaux intenses, des th\u00e9matiques de recherche ont \u00e9t\u00e9 identifi\u00e9es et une feuille de route \u00e9labor\u00e9e pour faciliter la conduite des activit\u00e9s. \u00ab Pour montrer son impact, le CNS bioagresseurs a int\u00e9r\u00eat \u00e0 conna\u00eetre les probl\u00e8mes existants, et ensuite s\u2019attaquer aux probl\u00e8mes que les autres centres de recherche intervenant sur les bioagresseurs n\u2019ont pas abord\u00e9. Il est \u00e9galement important \u00e0 ce centre de se focaliser sur les probl\u00e8mes phytosanitaires \u00e9mergents, \u00bb a orient\u00e9 Dr Rachidatou SIKIROU, membre du comit\u00e9 scientifique et technique du CORAF. Il convient de pr\u00e9ciser que le projet d\u2019installation du CNS bioagresseurs du Togo \u00e0 l\u2019ITRA est soutenu financi\u00e8rement par le groupe de la Banque Mondiale \u00e0 travers le Programme sur la R\u00e9silience du Syst\u00e8me Alimentaire en Afrique de l\u2019ouest (FSRP Togo).<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>S\u2019inscrivant dans la dynamique de CNS pr\u00f4n\u00e9 par le Conseil ouest et centre africain pour la recherche et le d\u00e9veloppement agricole (CORAF), le Togo, via l\u2019Institut Togolais de Recherche Agronomique (ITRA) se positionne sur les bioagresseurs. Dans l\u2019optique de prendre en compte les priorit\u00e9s de la sous-r\u00e9gion ouest africaine concernant les probl\u00e8mes li\u00e9s ravageurs et [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":15949,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"categories":[19],"tags":[],"class_list":["post-16111","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite","entry","has-media"],"_links":{"self":[{"href":"https:\/\/itra.tg\/index.php\/wp-json\/wp\/v2\/posts\/16111","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/itra.tg\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/itra.tg\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/itra.tg\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/itra.tg\/index.php\/wp-json\/wp\/v2\/comments?post=16111"}],"version-history":[{"count":3,"href":"https:\/\/itra.tg\/index.php\/wp-json\/wp\/v2\/posts\/16111\/revisions"}],"predecessor-version":[{"id":16263,"href":"https:\/\/itra.tg\/index.php\/wp-json\/wp\/v2\/posts\/16111\/revisions\/16263"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/itra.tg\/index.php\/wp-json\/wp\/v2\/media\/15949"}],"wp:attachment":[{"href":"https:\/\/itra.tg\/index.php\/wp-json\/wp\/v2\/media?parent=16111"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/itra.tg\/index.php\/wp-json\/wp\/v2\/categories?post=16111"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/itra.tg\/index.php\/wp-json\/wp\/v2\/tags?post=16111"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}